{"id":485,"date":"2018-08-09T14:15:24","date_gmt":"2018-08-09T14:15:24","guid":{"rendered":"http:\/\/hh.cregital.com\/?p=485"},"modified":"2019-05-21T14:16:12","modified_gmt":"2019-05-21T14:16:12","slug":"lafricapitalisme-une-nouvelle-ere-pour-lafrique","status":"publish","type":"post","link":"https:\/\/www.heirsholdings.com\/fr\/africapitalism-a-new-era-for-africa\/","title":{"rendered":"Africapitalisme : une nouvelle \u00e8re pour l\u2019Afrique"},"content":{"rendered":"<p>Jerry Petit-Frere, ancien stagiaire chez Heirs Holdings et actuellement en MBA \u00e0 Cornell, a \u00e9crit un article int\u00e9ressant sur l&#039;Africapitalisme.<\/p>\n\n\n\n<p>Lisez ses pens\u00e9es ci-dessous :<\/p>\n\n\n\n<p>L\u2019Afrique en tant que continent est un march\u00e9 \u00e9mergent depuis 20 ans.  L\u2019utilisation de la technologie moderne fait partie de certains des principaux progr\u00e8s r\u00e9alis\u00e9s en Afrique.  Toutefois, les infrastructures, la crise alimentaire et l\u2019\u00e9ducation restent \u00e0 la tra\u00eene.  Quelle est la solution pour aider l\u2019Afrique \u00e0 surmonter ces d\u00e9fis ? Selon Heirs Holdings, une soci\u00e9t\u00e9 d\u2019investissement nig\u00e9riane, l\u2019Africapitalisme est la solution qui fera avancer l\u2019Afrique.  L&#039;africapitalisme est d\u00e9fini comme l&#039;engagement du secteur priv\u00e9 en faveur du d\u00e9veloppement de l&#039;Afrique \u00e0 travers des investissements \u00e0 long terme dans des secteurs strat\u00e9giques de l&#039;\u00e9conomie qui cr\u00e9ent la prosp\u00e9rit\u00e9 \u00e9conomique et la richesse sociale.<\/p>\n\n\n\n<p>\u00c0 l&#039;\u00e9t\u00e9 2013, j&#039;ai eu le privil\u00e8ge d&#039;effectuer mon stage dans le cadre du programme de stages sur les march\u00e9s africains (AMIP) de la Fondation Tony Elumelu (TEF).  L&#039;Emerging Markets Institute a jou\u00e9 un r\u00f4le d\u00e9terminant dans ma mise en relation avec ce stage.  L&#039;Institut TEF est une filiale au sein de Heirs Holdings. Le programme AMIP place des stagiaires MBA du monde entier dans des PME en Afrique.  J&#039;ai effectu\u00e9 mon stage chez Bookworld, une cha\u00eene de librairies de d\u00e9tail \u00e0 Lusaka, en Zambie.<\/p>\n\n\n\n<p>Si l\u2019africapitalisme reste vrai, il reste encore un certain nombre de d\u00e9fis \u00e0 relever pour que l\u2019Afrique puisse se d\u00e9velopper avec succ\u00e8s avec une \u00e9conomie florissante.  Les deux principaux d\u00e9fis auxquels j&#039;ai \u00e9t\u00e9 confront\u00e9 au cours de mon stage et de mes voyages \u00e0 travers le continent sont la disponibilit\u00e9 limit\u00e9e de l&#039;industrie et des \u00e9tudes de march\u00e9 et le d\u00e9veloppement du capital humain.<\/p>\n\n\n\n<p>Au cours de ma premi\u00e8re ann\u00e9e chez Johnson, l&#039;immersion Sustainable Global Enterprise (SGE) et mes r\u00f4les de direction m&#039;ont bien pr\u00e9par\u00e9 \u00e0 relever ces d\u00e9fis.  Environ trente pour cent de mon projet de stage \u00e9tait ax\u00e9 sur la transformation organisationnelle.  En utilisant les cadres que j&#039;ai appris au cours de mon projet de conseil en immersion, j&#039;ai pu \u00e9valuer et r\u00e9soudre en profondeur les probl\u00e8mes structurels et proc\u00e9duraux auxquels l&#039;entreprise est confront\u00e9e.  De plus, l&#039;une de mes responsabilit\u00e9s \u00e9tait de cr\u00e9er une structure de primes et d&#039;incitations.  Pour mon pr\u00e9c\u00e9dent projet SGE, mon \u00e9quipe a cr\u00e9\u00e9 un ensemble d&#039;outils pour \u00e9valuer les facteurs de motivation d&#039;un casino \u00e0 Las Vegas.  J&#039;ai pu mettre \u00e0 profit ce que j&#039;ai appris et cr\u00e9er une \u00e9valuation similaire pour mieux comprendre ce qui motive les Zambiens mais en particulier les employ\u00e9s de Bookworld.  Cette \u00e9valuation est l&#039;outil qui a \u00e9t\u00e9 utilis\u00e9 pour cr\u00e9er des primes et des incitations.<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.johnson.cornell.edu\/Emerging-Markets-Institute\/Research\/EMI-at-Work\/Institute-at-Work-Article\/ArticleId\/24547\/Africapitalism-A-new-Era-for-Africa\" target=\"_blank\" rel=\"noopener\">Cliquez ici pour en lire plus<\/a><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Former Heirs Holdings Intern, Jerry Petit-Frere, currently undergoing his MBA at Cornell, wrote an interesting feature on Africapitalism. Read his thoughts below: Africa as a continent has been an emerging market for the past 20 years. &nbsp;The use of modern-day technology has been part of some of the leading advancements taking place in Africa. &nbsp;However, &hellip;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"cybocfi_hide_featured_image":"","footnotes":""},"categories":[9],"tags":[],"class_list":["post-485","post","type-post","status-publish","format-standard","hentry","category-articles"],"_links":{"self":[{"href":"https:\/\/www.heirsholdings.com\/fr\/wp-json\/wp\/v2\/posts\/485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.heirsholdings.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.heirsholdings.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.heirsholdings.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.heirsholdings.com\/fr\/wp-json\/wp\/v2\/comments?post=485"}],"version-history":[{"count":1,"href":"https:\/\/www.heirsholdings.com\/fr\/wp-json\/wp\/v2\/posts\/485\/revisions"}],"predecessor-version":[{"id":486,"href":"https:\/\/www.heirsholdings.com\/fr\/wp-json\/wp\/v2\/posts\/485\/revisions\/486"}],"wp:attachment":[{"href":"https:\/\/www.heirsholdings.com\/fr\/wp-json\/wp\/v2\/media?parent=485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.heirsholdings.com\/fr\/wp-json\/wp\/v2\/categories?post=485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.heirsholdings.com\/fr\/wp-json\/wp\/v2\/tags?post=485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}